{"id":45,"count":1,"description":"","link":"https:\/\/hotelaldebaran.it\/en\/tag\/hotel-vicino-alla-fiera-en\/","name":"hotel vicino alla fiera","slug":"hotel-vicino-alla-fiera-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>hotel vicino alla fiera Archivi - Hotel Aldebaran<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hotel vicino alla fiera Archivi - Hotel Aldebaran\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Aldebaran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/\",\"url\":\"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/\",\"name\":\"hotel vicino alla fiera Archivi - Hotel Aldebaran\",\"isPartOf\":{\"@id\":\"https:\/\/hotelaldebaran.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hotelaldebaran.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"hotel vicino alla fiera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hotelaldebaran.it\/#website\",\"url\":\"https:\/\/hotelaldebaran.it\/\",\"name\":\"Hotel Aldebaran\",\"description\":\"Family Hotel - Marina Centro, Rimini\",\"publisher\":{\"@id\":\"https:\/\/hotelaldebaran.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hotelaldebaran.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hotelaldebaran.it\/#organization\",\"name\":\"Hotel Aldebaran\",\"url\":\"https:\/\/hotelaldebaran.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hotelaldebaran.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hotelaldebaran.it\/wp-content\/uploads\/2025\/01\/Logo_Ald_tondo-removebg-preview-e1737470294262.png\",\"contentUrl\":\"https:\/\/hotelaldebaran.it\/wp-content\/uploads\/2025\/01\/Logo_Ald_tondo-removebg-preview-e1737470294262.png\",\"width\":258,\"height\":257,\"caption\":\"Hotel Aldebaran\"},\"image\":{\"@id\":\"https:\/\/hotelaldebaran.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"hotel vicino alla fiera Archivi - Hotel Aldebaran","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/","og_locale":"en_US","og_type":"article","og_title":"hotel vicino alla fiera Archivi - Hotel Aldebaran","og_url":"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/","og_site_name":"Hotel Aldebaran","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/","url":"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/","name":"hotel vicino alla fiera Archivi - Hotel Aldebaran","isPartOf":{"@id":"https:\/\/hotelaldebaran.it\/#website"},"breadcrumb":{"@id":"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hotelaldebaran.it\/tag\/hotel-vicino-alla-fiera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotelaldebaran.it\/en\/"},{"@type":"ListItem","position":2,"name":"hotel vicino alla fiera"}]},{"@type":"WebSite","@id":"https:\/\/hotelaldebaran.it\/#website","url":"https:\/\/hotelaldebaran.it\/","name":"Hotel Aldebaran","description":"Family Hotel - Marina Centro, Rimini","publisher":{"@id":"https:\/\/hotelaldebaran.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelaldebaran.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hotelaldebaran.it\/#organization","name":"Hotel Aldebaran","url":"https:\/\/hotelaldebaran.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hotelaldebaran.it\/#\/schema\/logo\/image\/","url":"https:\/\/hotelaldebaran.it\/wp-content\/uploads\/2025\/01\/Logo_Ald_tondo-removebg-preview-e1737470294262.png","contentUrl":"https:\/\/hotelaldebaran.it\/wp-content\/uploads\/2025\/01\/Logo_Ald_tondo-removebg-preview-e1737470294262.png","width":258,"height":257,"caption":"Hotel Aldebaran"},"image":{"@id":"https:\/\/hotelaldebaran.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotelaldebaran.it\/en\/wp-json\/wp\/v2\/tags\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelaldebaran.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hotelaldebaran.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hotelaldebaran.it\/en\/wp-json\/wp\/v2\/posts?tags=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}